{"id":984,"date":"2022-07-25T13:55:19","date_gmt":"2022-07-25T13:55:19","guid":{"rendered":"https:\/\/intelligent-game.flywheelsites.com\/quienes-somos\/"},"modified":"2022-11-08T17:26:22","modified_gmt":"2022-11-08T17:26:22","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/globalfellowsnetwork.org\/es\/quienes-somos\/","title":{"rendered":"Qui\u00e9nes somos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"984\" class=\"elementor elementor-984 elementor-24\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1221e7e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1221e7e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fba662d\" data-id=\"fba662d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84bb46d elementor-widget elementor-widget-heading\" data-id=\"84bb46d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Qui\u00e9nes somos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95bb23d elementor-widget elementor-widget-text-editor\" data-id=\"95bb23d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La WKKF ha invertido en el desarrollo de liderazgos durante m\u00e1s de 90 a\u00f1os. Si bien hemos apoyado muchos programas de becas, muchos dise\u00f1ados e implementados fuera de la WKKF, aqu\u00ed est\u00e1 la lista de programas de liderazgo exclusivos que forman parte de la Global Fellows Network de la WKKF. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2173053 elementor-widget elementor-widget-text-editor\" data-id=\"2173053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Si consideras que eres una o un fellow y deseas obtener m\u00e1s informaci\u00f3n, comun\u00edcate con nosotros.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9437db9 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9437db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/es\/unete-a-nosotros\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cont\u00e1ctanos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-058f6c2\" data-id=\"058f6c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b32aa2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b32aa2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be1266a\" data-id=\"be1266a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55e104b elementor-widget elementor-widget-heading\" data-id=\"55e104b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">N\u00fameros de la red<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b52154b elementor-widget elementor-widget-text-editor\" data-id=\"b52154b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una instant\u00e1nea de la Global Fellows Network por los n\u00fameros.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-30abdfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30abdfa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-47413b8\" data-id=\"47413b8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8a3c57 elementor-widget elementor-widget-counter\" data-id=\"c8a3c57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Fellows<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1141\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3d67676\" data-id=\"3d67676\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c4ccd5 elementor-widget elementor-widget-counter\" data-id=\"5c4ccd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Pa\u00edses<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"44\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8aa4a5d\" data-id=\"8aa4a5d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-552bc90 elementor-widget elementor-widget-counter\" data-id=\"552bc90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Programas<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"17\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ff04f0 elementor-widget elementor-widget-text-editor\" data-id=\"5ff04f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estos programas representan m\u00e1s de 40 a\u00f1os de desarrollo de liderazgo en m\u00e1s de 40 pa\u00edses.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9610f88 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9610f88\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bc31fd\" data-id=\"5bc31fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e39ec6 elementor-widget elementor-widget-heading\" data-id=\"3e39ec6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Donde estamos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7d66d2 elementor-widget elementor-widget-text-editor\" data-id=\"f7d66d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Global Fellows Network es una comunidad de m\u00e1s de 1100 agentes de cambio, l\u00edderes de opini\u00f3n y personas influyentes de m\u00e1s de 40 pa\u00edses, que representan diversos or\u00edgenes, sectores y generaciones. Est\u00e1n trabajando para lograr un cambio transformador en todo el mundo y la mayor\u00eda se encuentra en Am\u00e9rica Latina y el Caribe, el sur de \u00c1frica y los Estados Unidos. En los \u00faltimos a\u00f1os, nuestro programa de liderazgo exclusivo, la Red de Liderazgo Comunitario, se ha centrado en desarrollar liderazgos en los Estados Unidos y las tribus soberanas, especialmente en nuestros lugares prioritarios: Michigan, Mississippi, Nuevo M\u00e9xico y Nueva Orleans. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a79b80b elementor-widget elementor-widget-html\" data-id=\"a79b80b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\" src=\"https:\/\/tableau.wkkf.org\/javascripts\/api\/viz_v1.js\"><\/script><div class=\"tableauPlaceholder\" style=\"width: 1200px; height: 827px;\"><object class=\"tableauViz\" width=\"1200\" height=\"827\" style=\"display:none;\"><param name=\"host_url\" value=\"https%3A%2F%2Ftableau.wkkf.org%2F\"> <param name=\"embed_code_version\" value=\"3\"> <param name=\"site_root\" value=\"\"><param name=\"name\" value=\"GranteeFellowsNetwork\/GlobalFellowMap\"><param name=\"tabs\" value=\"no\"><param name=\"toolbar\" value=\"s\u00ed\"><param name=\"showAppBanner\" value=\"falso\"><\/object><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-219ab68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"219ab68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53d020c\" data-id=\"53d020c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-deb3175 elementor-widget elementor-widget-heading\" data-id=\"deb3175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Programas de becas de la Fundaci\u00f3n W.K. Kellogg <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd7ba86 elementor-widget elementor-widget-text-editor\" data-id=\"bd7ba86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desde nuestra fundaci\u00f3n en 1930, la Fundaci\u00f3n W.K. Kellogg (WKKF) se ha comprometido a desarrollar liderazgos a nivel mundial, al darse cuenta de que el cambio ocurre a nivel comunitario. Si bien hemos financiado muchos programas de becas a lo largo de los a\u00f1os, aqu\u00ed est\u00e1 la lista de programas formales que forman parte de la Global Fellows Network de la WKKF.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ab0261e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab0261e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c04ab8e\" data-id=\"c04ab8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8676a9d elementor-widget elementor-widget-timeline-widget-addon\" data-id=\"8676a9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"timeline-widget-addon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- ========= Timeline Widget Pro For Elementor 1.8.1 ========= -->\r\n<div id=\"twae-wrapper-8676a9d\" data-style=\"style-1\" data-enable-popup=\"no\" data-space=\"60\" data-line-filling=\"on\" class=\"twae-vertical twae-wrapper twae-both-sided style-1 twae-bg-simple\">   \r\n    <div class=\"twae-start\"><\/div>    \r\n    <div id=\"twae-line-8676a9d\" data-style=\"style-1\" data-line_id=\"twae-line-8676a9d\" class=\"twae-line twae-timeline twae-compact\" ><div id=\"twae-d693ae2\" class=\"twae-story elementor-repeater-item-d693ae2 twae-repeater-item twae-story-right twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 1980-2002<\/div><div class=\"twae-label-small\">N\u00famero de participantes: 706<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Programa Nacional de Becas\/Liderazgo Kellogg (KNLP)<\/div><div class=\"twae-media full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-knpl.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-knpl.jpg 800w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-knpl-300x166.jpg 300w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-knpl-768x425.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"twae-description\">Administrado directamente por la WKKF, este programa incluy\u00f3 16 cohortes de fellows de los Estados Unidos. Fue dise\u00f1ado para proporcionar crecimiento personal y profesional durante un per\u00edodo de tres a\u00f1os, ampliando el conocimiento y la capacidad de los l\u00edderes a trav\u00e9s de seminarios, aprendizaje experimental individual y en grupos peque\u00f1os, estudios de viajes y tutor\u00eda. Com\u00fanmente conocido como Programa Nacional de Liderazgo, el programa cambi\u00f3 de nombre de Programa Nacional de Becas Kellogg a Programa Nacional de Liderazgo Kellogg.<\/div><\/div><\/div><div id=\"twae-8fce38b\" class=\"twae-story elementor-repeater-item-8fce38b twae-repeater-item twae-story-left twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 1986-1990<\/div><div class=\"twae-label-small\">N\u00famero de participantes: 22<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Programa de Becas Internacionales Kellogg\/Salud (KIFP\/H)<\/div><div class=\"twae-description\">Administrado a trav\u00e9s del Instituto de Salud Internacional de la Universidad Estatal de Michigan, el programa incluy\u00f3 fellows de 18 pa\u00edses y cinco continentes y se centr\u00f3 en programas de educaci\u00f3n m\u00e9dica orientados a la comunidad y atenci\u00f3n primaria de la salud.<\/div><\/div><\/div><div id=\"twae-cc5020d\" class=\"twae-story elementor-repeater-item-cc5020d twae-repeater-item twae-story-right twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 1986-1990<\/div><div class=\"twae-label-small\">ero de participantes: 32<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Programa de Becas Internacionales Kellogg\/Sistemas Alimentarios (KIFP\/HS)<\/div><div class=\"twae-description\">Administrado a trav\u00e9s del Instituto de Agricultura Internacional de la Universidad Estatal de Michigan, el programa apoy\u00f3 a becarios de Am\u00e9rica del Sur, \u00c1frica y Asia para mejorar sus habilidades de liderazgo para ayudar a mejorar los sistemas alimentarios para los hogares de bajos ingresos en los pa\u00edses en desarrollo.<\/div><\/div><\/div><div id=\"twae-36b96fa\" class=\"twae-story elementor-repeater-item-36b96fa twae-repeater-item twae-story-left twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 1986-2013<\/div><div class=\"twae-label-small\">ero de participantes: 87<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Fellows de Alimentaci\u00f3n<\/div><div class=\"twae-media full\"><img decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-foodfellow.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-foodfellow.jpg 800w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-foodfellow-300x166.jpg 300w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-foodfellow-768x425.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"twae-description\"><p>El Instituto Jefferson y el Instituto de Pol\u00edticas Agr\u00edcolas y Comerciales (IATP) administraron tres programas: Becas de Pol\u00edticas de Alimentaci\u00f3n y Sociedad (FSPF, por sus siglas en ingl\u00e9s), Becas de Pol\u00edticas y Alimentos (FBF) y Becas de Alimentos y Comunidades (FCF). Los programas reunieron a fellows de los Estados Unidos con experiencia en agricultura, salud p\u00fablica, periodismo, cine e investigaci\u00f3n en pol\u00edticas. Cada cohorte incluy\u00f3 hasta 12 fellows que participaron en una experiencia de dos a\u00f1os para incidir en la pol\u00edtica local, regional y nacional a trav\u00e9s de esfuerzos de comunicaci\u00f3n estrat\u00e9gica. La beca incluy\u00f3 capacitaci\u00f3n en medios, aprendizaje experimental y seminarios que mejoraron las habilidades y profundizaron la comprensi\u00f3n sobre cuestiones de pol\u00edtica alimentaria y agr\u00edcola.<\/p><p><strong>El FSPF<\/strong> abord\u00f3 los problemas y desaf\u00edos asociados con el mantenimiento de las granjas familiares y la producci\u00f3n de alimentos en los Estados Unidos.<\/p><p><strong>El FBF<\/strong> se centr\u00f3 en el uso de los canales de los medios de comunicaci\u00f3n para informar y dar forma a la agenda p\u00fablica de alimentaci\u00f3n y para catalizar cambios culturales y de pol\u00edticas.<\/p><p><strong>El FCF<\/strong> se centr\u00f3 en asuntos de justicia alimentaria, fortaleciendo los esfuerzos para eliminar los desiertos de comida, creando entornos alimentarios saludables para las ni\u00f1as y ni\u00f1os e identificando y eliminando los factores sociales que crean desventajas para la salud de todas las infancias.<\/p><\/div><\/div><\/div><div id=\"twae-f86d54c\" class=\"twae-story elementor-repeater-item-f86d54c twae-repeater-item twae-story-right twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 1989-1998<\/div><div class=\"twae-label-small\">ero de participantes: 105<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Programa de Liderazgo Internacional de Kellogg (KILP)<\/div><div class=\"twae-media full\"><img decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-kilp.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-kilp.jpg 800w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-kilp-300x166.jpg 300w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-kilp-768x425.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"twae-description\">Administrado directamente por la WKKF, el programa apoy\u00f3 a dos grupos de becarios de los Estados Unidos, Am\u00e9rica Central y del Sur y \u00c1frica en un viaje de liderazgo de tres a\u00f1os. El objetivo era promover la capacidad de liderazgo para los servicios humanos en todo el mundo.<\/div><\/div><\/div><div id=\"twae-971c438\" class=\"twae-story elementor-repeater-item-971c438 twae-repeater-item twae-story-left twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 1991-1996<\/div><div class=\"twae-label-small\">ero de participantes: 15<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Alianzas comunitarias en educaci\u00f3n con profesionales de la salud (CPHPE)<\/div><div class=\"twae-description\">Administrado a trav\u00e9s de universidades en siete estados de Estados Unidos (Georgia, Hawai, Massachusetts, Michigan, Tennessee, Texas y Virginia Occidental), el programa promovi\u00f3 un enfoque centrado en la comunidad, coordinando la investigaci\u00f3n de salud basada en la comunidad, fomentando la colaboraci\u00f3n interdisciplinaria y vinculando a los trabajadores de la salud con miembros locales. Como resultado, se hicieron 103 cambios en pol\u00edticas.<\/div><\/div><\/div><div id=\"twae-1b2a48d\" class=\"twae-story elementor-repeater-item-1b2a48d twae-repeater-item twae-story-right twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 1998-2012<\/div><div class=\"twae-label-small\">ero de participantes: 164<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Fellows Acad\u00e9micos de Salud (HFS)<\/div><div class=\"twae-media full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-hfs.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-hfs.jpg 800w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-hfs-300x166.jpg 300w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-hfs-768x425.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"twae-description\"><p>Fellows Acad\u00e9micos de Salud incluye tres programas: Programa Acad\u00e9mico de Salud Comunitaria (CHSP), Programa Acad\u00e9mico en Disparidades de Salud (SHDP) y Kellogg Fellows en Investigaci\u00f3n en Pol\u00edticas de Salud. El programa de becas de dos a\u00f1os capacit\u00f3 a un cuadro de l\u00edderes en habilidades para la investigaci\u00f3n sobre los determinantes sociales de la salud, la relaci\u00f3n entre la academia y la comunidad, la investigaci\u00f3n participativa basada en la comunidad y la aplicaci\u00f3n de la investigaci\u00f3n para fortalecer la incidencia y lograr cambios en las pol\u00edticas. En 2006, los programas se combinaron para crear el Programa de Becarios de Salud de Kellogg.<\/p><p><strong>CHSP<\/strong> se estableci\u00f3 en 1998 y funcion\u00f3 hasta 2007. Administrado a trav\u00e9s de la Universidad de Michigan, capacit\u00f3 a 46 fellows posdoctorales para trabajar con comunidades y participar en investigaciones participativas basadas en la comunidad.<\/p><p><strong>SHDP<\/strong> fue administrado por el Centro para el Avance de la Salud desde 2001-2012. El programa se centr\u00f3 en desarrollar nuevos liderazgos y capacitar a futuros profesores y legisladores en el esfuerzo por reducir y eliminar las disparidades de salud.<\/p><p>Kellogg Fellows en Investigaci\u00f3n en Pol\u00edticas de Salud fue administrado por el Centro para el Avance de la Salud de 1990 a 2012. Un programa postdoctoral, se centr\u00f3 en reducir las disparidades de salud y crear asociaciones entre las comunidades y los programas de educaci\u00f3n para la salud.<\/p><\/div><\/div><\/div><div id=\"twae-a3dfc9f\" class=\"twae-story elementor-repeater-item-a3dfc9f twae-repeater-item twae-story-left twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 2000-2019<\/div><div class=\"twae-label-small\">ero de participantes: 164<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Programa de Becas de Liderazgo Social de Am\u00e9rica Latina y el Caribe (LASPAU)<\/div><div class=\"twae-media full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-laspau.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-laspau.jpg 800w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-laspau-300x166.jpg 300w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-laspau-768x425.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"twae-description\">Administrado por LASPAU, afiliado a Harvard, el programa empoder\u00f3 a los liderazgos locales para abordar problemas sociales en sus respectivas comunidades a trav\u00e9s de la financiaci\u00f3n de sus actividades educativas. Los l\u00edderes proced\u00edan de Am\u00e9rica Latina, incluidas las \u00e1reas de Chiapas y la pen\u00ednsula de Yucat\u00e1n en M\u00e9xico y el centro y suroeste de Hait\u00ed.<\/div><\/div><\/div><div id=\"twae-9d9bb17\" class=\"twae-story elementor-repeater-item-9d9bb17 twae-repeater-item twae-story-right twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 2003-2014<\/div><div class=\"twae-label-small\">ero de participantes: 230<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Programa de Liderazgo de \u00c1frica Meridional de Kellogg (KSAL)<\/div><div class=\"twae-media full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-ksal.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-ksal.jpg 800w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-ksal-300x166.jpg 300w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-ksal-768x425.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"twae-description\">Administrado por La Academia para el Desarrollo Educacional  y luego por Salud y Familia Internacional,  el programa oper\u00f3 en siete pa\u00edses (Botswana, Lesotho, Malawi, Mozambique, Sud\u00e1frica, Swazilandia y Zimbabwe) y promovi\u00f3 un liderazgo \u00e9tico, democr\u00e1tico y basado en valores. Se centr\u00f3 en la creaci\u00f3n de un cuadro de l\u00edderes din\u00e1micos en todo el sur de \u00c1frica mediante la prestaci\u00f3n de asistencia financiera educativa para programas de posgrado y pregrado y desarrollo de liderazgo.<\/div><\/div><\/div><div id=\"twae-7c11d9d\" class=\"twae-story elementor-repeater-item-7c11d9d twae-repeater-item twae-story-left twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 2010-2012<\/div><div class=\"twae-label-small\">ero de participantes: 53<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Kellogg Programa de Fortalecimiento \/ Liderazgo (Kellogg Program for Leadership Development) (KPFL)<\/div><div class=\"twae-description\">Administrado a trav\u00e9s de GC Genera, el programa brind\u00f3 capacitaci\u00f3n en desarrollo de liderazgo a l\u00edderes locales de Chiapas y la pen\u00ednsula de Yucat\u00e1n en M\u00e9xico. El programa incluy\u00f3 dos cohortes, cada una con una duraci\u00f3n de 10 meses, donde los becarios se conectaron con l\u00edderes locales y regionales y aprendieron sobre proyectos de desarrollo comunitario.<\/div><\/div><\/div><div id=\"twae-dc6c2b1\" class=\"twae-story elementor-repeater-item-dc6c2b1 twae-repeater-item twae-story-right twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 2011-2014<\/div><div class=\"twae-label-small\">ero de participantes: 24<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Programa de Desarrollo de Liderazgo para la Igualdad Racial y de G\u00e9nero - Nordeste de Brasil (KWETU)<\/div><div class=\"twae-description\">Administrado por el Instituto Cultural Steve Biko, el programa apoy\u00f3 a l\u00edderes y organizaciones del noreste de Brasil para promover cambios estructurales en la cultura brasile\u00f1a relacionados con la igualdad racial y de g\u00e9nero. Solo hab\u00eda una cohorte para este programa.<\/div><\/div><\/div><div id=\"twae-adf5e27\" class=\"twae-story elementor-repeater-item-adf5e27 twae-repeater-item twae-story-left twae-story-icon \"><div class=\"twae-labels \" data-aos=\"none\"><div class=\"twae-label-big\">A\u00f1os Activo: 2014-present<\/div><div class=\"twae-label-small\">ero de participantes: 199<\/div><\/div><div class=\"twae-icon\"><i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i><\/div><div class=\"twae-arrow-line\" ><\/div><div class=\"twae-content\"  data-aos=\"none\"><div class=\"twae-title\">Red de Liderazgo Comunitario WKKF (CLN)<\/div><div class=\"twae-media full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-cln.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-cln.jpg 800w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-cln-300x166.jpg 300w, https:\/\/globalfellowsnetwork.org\/wp-content\/uploads\/2022\/09\/GFN-time-cln-768x425.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"twae-description\">Administrado en asociaci\u00f3n con el Centro para el Liderazgo Creativo, este es nuestro programa de liderazgo m\u00e1s reciente en los Estados Unidos. El programa apoya a l\u00edderes emergentes y l\u00edderes establecidos para conectarse, crecer y liderar un cambio transformador hacia una sociedad m\u00e1s equitativa. Se hace especial \u00e9nfasis en los lugares prioritarios de la WKKF: Michigan, Mississippi, New Mexico y New Orleans.<\/div><\/div><\/div><div class=\"twae-inner-line\"><\/div><\/div>\r\n<div class=\"twae-end\"><\/div>   \r\n<\/div><style type=\"text\/css\"><\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Qui\u00e9nes somos La WKKF ha invertido en el desarrollo de liderazgos durante m\u00e1s de 90 a\u00f1os. Si bien hemos apoyado muchos programas de becas, muchos dise\u00f1ados e implementados fuera de la WKKF, aqu\u00ed est\u00e1 la lista de programas de liderazgo exclusivos que forman parte de la Global Fellows Network de la WKKF. Si consideras que &#8230; <a title=\"Qui\u00e9nes somos\" class=\"read-more\" href=\"https:\/\/globalfellowsnetwork.org\/es\/quienes-somos\/\" aria-label=\"Read more about Qui\u00e9nes somos\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-984","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/globalfellowsnetwork.org\/es\/wp-json\/wp\/v2\/pages\/984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalfellowsnetwork.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/globalfellowsnetwork.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/globalfellowsnetwork.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/globalfellowsnetwork.org\/es\/wp-json\/wp\/v2\/comments?post=984"}],"version-history":[{"count":0,"href":"https:\/\/globalfellowsnetwork.org\/es\/wp-json\/wp\/v2\/pages\/984\/revisions"}],"wp:attachment":[{"href":"https:\/\/globalfellowsnetwork.org\/es\/wp-json\/wp\/v2\/media?parent=984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}